{"id":900,"date":"2025-01-01T01:49:58","date_gmt":"2025-01-01T01:49:58","guid":{"rendered":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/"},"modified":"2025-01-01T01:49:58","modified_gmt":"2025-01-01T01:49:58","slug":"neuro-clerk-sim-6","status":"publish","type":"tribe_events","link":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/","title":{"rendered":"Neuro Clerk Sim"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3600,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-900","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Neuro Clerk Sim - Rutgers Health Emergency Medicine Simulation Fellowship<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuro Clerk Sim - Rutgers Health Emergency Medicine Simulation Fellowship\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Rutgers Health Emergency Medicine Simulation Fellowship\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/\",\"url\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/\",\"name\":\"Neuro Clerk Sim - Rutgers Health Emergency Medicine Simulation Fellowship\",\"isPartOf\":{\"@id\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/#website\"},\"datePublished\":\"2025-01-01T01:49:58+00:00\",\"dateModified\":\"2025-01-01T01:49:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Neuro Clerk Sim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/#website\",\"url\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/\",\"name\":\"Rutgers Health Emergency Medicine Simulation Fellowship\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sites.rutgers.edu\/emsim-fellowship\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuro Clerk Sim - Rutgers Health Emergency Medicine Simulation Fellowship","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/","og_locale":"en_US","og_type":"article","og_title":"Neuro Clerk Sim - Rutgers Health Emergency Medicine Simulation Fellowship","og_url":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/","og_site_name":"Rutgers Health Emergency Medicine Simulation Fellowship","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/","url":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/","name":"Neuro Clerk Sim - Rutgers Health Emergency Medicine Simulation Fellowship","isPartOf":{"@id":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/#website"},"datePublished":"2025-01-01T01:49:58+00:00","dateModified":"2025-01-01T01:49:58+00:00","breadcrumb":{"@id":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/event\/neuro-clerk-sim-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/events\/"},{"@type":"ListItem","position":3,"name":"Neuro Clerk Sim"}]},{"@type":"WebSite","@id":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/#website","url":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/","name":"Rutgers Health Emergency Medicine Simulation Fellowship","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/tribe_events\/900"}],"collection":[{"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/users\/3600"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":0,"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/tribe_events\/900\/revisions"}],"wp:attachment":[{"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/media?parent=900"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/tags?post=900"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/sites.rutgers.edu\/emsim-fellowship\/wp-json\/wp\/v2\/tribe_events_cat?post=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}