{"id":157,"count":21,"description":"","link":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/","name":"Gastronomie","slug":"gastronomie","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gastronomie Archives - La P&#039;tite Gazette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastronomie Archives - La P&#039;tite Gazette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/\" \/>\n<meta property=\"og:site_name\" content=\"La P&#039;tite Gazette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/\",\"url\":\"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/\",\"name\":\"Gastronomie Archives - La P&#039;tite Gazette\",\"isPartOf\":{\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sites.rutgers.edu\/french-magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastronomie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#website\",\"url\":\"https:\/\/sites.rutgers.edu\/french-magazine\/\",\"name\":\"La P&#039;tite Gazette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sites.rutgers.edu\/french-magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastronomie Archives - La P&#039;tite Gazette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/","og_locale":"en_US","og_type":"article","og_title":"Gastronomie Archives - La P&#039;tite Gazette","og_url":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/","og_site_name":"La P&#039;tite Gazette","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/","url":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/","name":"Gastronomie Archives - La P&#039;tite Gazette","isPartOf":{"@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#website"},"breadcrumb":{"@id":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/category\/gastronomie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.rutgers.edu\/french-magazine\/"},{"@type":"ListItem","position":2,"name":"Gastronomie"}]},{"@type":"WebSite","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#website","url":"https:\/\/sites.rutgers.edu\/french-magazine\/","name":"La P&#039;tite Gazette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.rutgers.edu\/french-magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/categories\/157"}],"collection":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/posts?categories=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}