{"id":5305,"date":"2026-05-11T20:32:41","date_gmt":"2026-05-12T00:32:41","guid":{"rendered":"https:\/\/sites.rutgers.edu\/french-magazine\/?p=5305"},"modified":"2026-05-11T20:51:37","modified_gmt":"2026-05-12T00:51:37","slug":"le-cafe-des-chats-a-paris","status":"publish","type":"post","link":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/","title":{"rendered":"Le Caf\u00e9 des Chats \u00e0 Paris"},"content":{"rendered":"<div style=\"width: 720px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-5305-1\" width=\"720\" height=\"1280\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/sites.rutgers.edu\/french-magazine\/wp-content\/uploads\/sites\/592\/2026\/05\/Le-Caf-des-Chats-2.mp4?_=1\" \/><a href=\"http:\/\/sites.rutgers.edu\/french-magazine\/wp-content\/uploads\/sites\/592\/2026\/05\/Le-Caf-des-Chats-2.mp4\">http:\/\/sites.rutgers.edu\/french-magazine\/wp-content\/uploads\/sites\/592\/2026\/05\/Le-Caf-des-Chats-2.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4534,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[457],"tags":[],"class_list":["post-5305","post","type-post","status-publish","format-video","hentry","category-shorts","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Caf\u00e9 des Chats \u00e0 Paris - La P&#039;tite Gazette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Caf\u00e9 des Chats \u00e0 Paris - La P&#039;tite Gazette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"La P&#039;tite Gazette\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T00:32:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T00:51:37+00:00\" \/>\n<meta name=\"author\" content=\"Maeva Roquebert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maeva Roquebert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/\",\"url\":\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/\",\"name\":\"Le Caf\u00e9 des Chats \u00e0 Paris - La P&#039;tite Gazette\",\"isPartOf\":{\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#website\"},\"datePublished\":\"2026-05-12T00:32:41+00:00\",\"dateModified\":\"2026-05-12T00:51:37+00:00\",\"author\":{\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#\/schema\/person\/387d6abadaf21651cd7e43719f1acfe6\"},\"breadcrumb\":{\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sites.rutgers.edu\/french-magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Caf\u00e9 des Chats \u00e0 Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#website\",\"url\":\"https:\/\/sites.rutgers.edu\/french-magazine\/\",\"name\":\"La P&#039;tite Gazette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sites.rutgers.edu\/french-magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#\/schema\/person\/387d6abadaf21651cd7e43719f1acfe6\",\"name\":\"Maeva Roquebert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sites.rutgers.edu\/french-magazine\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/68f07e90dfec2d7fa21c85b041fad19d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/68f07e90dfec2d7fa21c85b041fad19d?s=96&d=mm&r=g\",\"caption\":\"Maeva Roquebert\"},\"url\":\"https:\/\/sites.rutgers.edu\/french-magazine\/author\/mr2347\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Caf\u00e9 des Chats \u00e0 Paris - La P&#039;tite Gazette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/","og_locale":"en_US","og_type":"article","og_title":"Le Caf\u00e9 des Chats \u00e0 Paris - La P&#039;tite Gazette","og_url":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/","og_site_name":"La P&#039;tite Gazette","article_published_time":"2026-05-12T00:32:41+00:00","article_modified_time":"2026-05-12T00:51:37+00:00","author":"Maeva Roquebert","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maeva Roquebert","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/","url":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/","name":"Le Caf\u00e9 des Chats \u00e0 Paris - La P&#039;tite Gazette","isPartOf":{"@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#website"},"datePublished":"2026-05-12T00:32:41+00:00","dateModified":"2026-05-12T00:51:37+00:00","author":{"@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#\/schema\/person\/387d6abadaf21651cd7e43719f1acfe6"},"breadcrumb":{"@id":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/le-cafe-des-chats-a-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.rutgers.edu\/french-magazine\/"},{"@type":"ListItem","position":2,"name":"Le Caf\u00e9 des Chats \u00e0 Paris"}]},{"@type":"WebSite","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#website","url":"https:\/\/sites.rutgers.edu\/french-magazine\/","name":"La P&#039;tite Gazette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.rutgers.edu\/french-magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#\/schema\/person\/387d6abadaf21651cd7e43719f1acfe6","name":"Maeva Roquebert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sites.rutgers.edu\/french-magazine\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/68f07e90dfec2d7fa21c85b041fad19d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68f07e90dfec2d7fa21c85b041fad19d?s=96&d=mm&r=g","caption":"Maeva Roquebert"},"url":"https:\/\/sites.rutgers.edu\/french-magazine\/author\/mr2347\/"}]}},"_links":{"self":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/posts\/5305"}],"collection":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/users\/4534"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/comments?post=5305"}],"version-history":[{"count":3,"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/posts\/5305\/revisions"}],"predecessor-version":[{"id":5309,"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/posts\/5305\/revisions\/5309"}],"wp:attachment":[{"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/media?parent=5305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/categories?post=5305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.rutgers.edu\/french-magazine\/wp-json\/wp\/v2\/tags?post=5305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}